{"id":229,"count":1,"description":"","link":"https:\/\/carsofq8.com\/ads\/tag\/%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9\/","name":"\u0648\u0646\u0634 \u0633\u0637\u062d\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u0644\u064a\u0629","slug":"%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/carsofq8.com\/ads\/tag\/%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/229\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carsofq8.com\\\/ads\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/tag\\\/%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9\\\/#listItem\",\"name\":\"\\u0648\\u0646\\u0634 \\u0633\\u0637\\u062d\\u0629 \\u0641\\u064a \\u0627\\u0644\\u0639\\u062f\\u064a\\u0644\\u064a\\u0629\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/tag\\\/%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9\\\/#listItem\",\"position\":2,\"name\":\"\\u0648\\u0646\\u0634 \\u0633\\u0637\\u062d\\u0629 \\u0641\\u064a \\u0627\\u0644\\u0639\\u062f\\u064a\\u0644\\u064a\\u0629\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/229\\\/#collectionpage\",\"url\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/229\\\/\",\"name\":\"\\u0648\\u0646\\u0634 \\u0633\\u0637\\u062d\\u0629 \\u0641\\u064a \\u0627\\u0644\\u0639\\u062f\\u064a\\u0644\\u064a\\u0629 | \\u062a\\u0627\\u0643\\u0633\\u064a \\u062a\\u0648\\u0635\\u064a\\u0644\\u0629 \\u0627\\u0644\\u0643\\u0648\\u064a\\u062a\",\"inLanguage\":\"ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/229\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/#organization\",\"name\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u062a\\u0648\\u0635\\u064a\\u0644\\u0629 \\u0627\\u0644\\u0643\\u0648\\u064a\\u062a\",\"description\":\"\\u0627\\u0631\\u0642\\u0627\\u0645 \\u062a\\u0627\\u0643\\u0633\\u064a \\u0648\\u0628\\u062f\\u0627\\u0644\\u0629 \\u062a\\u0643\\u0627\\u0633\\u064a \\u0623\\u062c\\u0631\\u0629 \\u062a\\u062d\\u062a \\u0627\\u0644\\u0637\\u0644\\u0628\",\"url\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/carsofq8.com\\\/ads\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/TAWSILA-TAXI-400.png?fit=400%2C223&ssl=1\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/229\\\/#organizationLogo\",\"width\":400,\"height\":223,\"caption\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u062a\\u0648\\u0635\\u064a\\u0644\\u0629 \\u0627\\u0644\\u0643\\u0648\\u064a\\u062a\"},\"image\":{\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/229\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/#website\",\"url\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/\",\"name\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u062a\\u0648\\u0635\\u064a\\u0644\\u0629 \\u0627\\u0644\\u0643\\u0648\\u064a\\u062a\",\"description\":\"\\u0627\\u0631\\u0642\\u0627\\u0645 \\u062a\\u0627\\u0643\\u0633\\u064a \\u0648\\u0628\\u062f\\u0627\\u0644\\u0629 \\u062a\\u0643\\u0627\\u0633\\u064a \\u0623\\u062c\\u0631\\u0629 \\u062a\\u062d\\u062a \\u0627\\u0644\\u0637\\u0644\\u0628\",\"inLanguage\":\"ar\",\"publisher\":{\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0648\u0646\u0634 \u0633\u0637\u062d\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u0644\u064a\u0629 | \u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a","description":"","canonical_url":"https:\/\/carsofq8.com\/ads\/tag\/%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/229\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carsofq8.com\/ads#listItem","position":1,"name":"Home","item":"https:\/\/carsofq8.com\/ads","nextItem":{"@type":"ListItem","@id":"https:\/\/carsofq8.com\/ads\/tag\/%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9\/#listItem","name":"\u0648\u0646\u0634 \u0633\u0637\u062d\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u0644\u064a\u0629"}},{"@type":"ListItem","@id":"https:\/\/carsofq8.com\/ads\/tag\/%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9\/#listItem","position":2,"name":"\u0648\u0646\u0634 \u0633\u0637\u062d\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u0644\u064a\u0629","previousItem":{"@type":"ListItem","@id":"https:\/\/carsofq8.com\/ads#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/229\/#collectionpage","url":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/229\/","name":"\u0648\u0646\u0634 \u0633\u0637\u062d\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u0644\u064a\u0629 | \u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a","inLanguage":"ar","isPartOf":{"@id":"https:\/\/carsofq8.com\/ads\/#website"},"breadcrumb":{"@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/229\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/carsofq8.com\/ads\/#organization","name":"\u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a","description":"\u0627\u0631\u0642\u0627\u0645 \u062a\u0627\u0643\u0633\u064a \u0648\u0628\u062f\u0627\u0644\u0629 \u062a\u0643\u0627\u0633\u064a \u0623\u062c\u0631\u0629 \u062a\u062d\u062a \u0627\u0644\u0637\u0644\u0628","url":"https:\/\/carsofq8.com\/ads\/","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/carsofq8.com\/ads\/wp-content\/uploads\/2020\/02\/TAWSILA-TAXI-400.png?fit=400%2C223&ssl=1","@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/229\/#organizationLogo","width":400,"height":223,"caption":"\u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a"},"image":{"@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/229\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/carsofq8.com\/ads\/#website","url":"https:\/\/carsofq8.com\/ads\/","name":"\u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a","description":"\u0627\u0631\u0642\u0627\u0645 \u062a\u0627\u0643\u0633\u064a \u0648\u0628\u062f\u0627\u0644\u0629 \u062a\u0643\u0627\u0633\u064a \u0623\u062c\u0631\u0629 \u062a\u062d\u062a \u0627\u0644\u0637\u0644\u0628","inLanguage":"ar","publisher":{"@id":"https:\/\/carsofq8.com\/ads\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/carsofq8.com\/ads\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0648\u0646\u0634 \u0633\u0637\u062d\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u0644\u064a\u0629\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/carsofq8.com\/ads"},{"label":"\u0648\u0646\u0634 \u0633\u0637\u062d\u0629 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u0644\u064a\u0629","link":"https:\/\/carsofq8.com\/ads\/tag\/%d9%88%d9%86%d8%b4-%d8%b3%d8%b7%d8%ad%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d8%af%d9%8a%d9%84%d9%8a%d8%a9\/"}],"_links":{"self":[{"href":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/posts?tags=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}