{"id":89,"count":4,"description":"","link":"https:\/\/carsofq8.com\/ads\/tag\/%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81\/","name":"\u062a\u0627\u0643\u0633\u064a \u0641\u064a \u0645\u0634\u0631\u0641","slug":"%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/carsofq8.com\/ads\/tag\/%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/89\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carsofq8.com\\\/ads\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/tag\\\/%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81\\\/#listItem\",\"name\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u0641\\u064a \\u0645\\u0634\\u0631\\u0641\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/tag\\\/%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81\\\/#listItem\",\"position\":2,\"name\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u0641\\u064a \\u0645\\u0634\\u0631\\u0641\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/89\\\/#collectionpage\",\"url\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/89\\\/\",\"name\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u0641\\u064a \\u0645\\u0634\\u0631\\u0641 | \\u062a\\u0627\\u0643\\u0633\\u064a \\u062a\\u0648\\u0635\\u064a\\u0644\\u0629 \\u0627\\u0644\\u0643\\u0648\\u064a\\u062a\",\"inLanguage\":\"ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/89\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/#organization\",\"name\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u062a\\u0648\\u0635\\u064a\\u0644\\u0629 \\u0627\\u0644\\u0643\\u0648\\u064a\\u062a\",\"description\":\"\\u0627\\u0631\\u0642\\u0627\\u0645 \\u062a\\u0627\\u0643\\u0633\\u064a \\u0648\\u0628\\u062f\\u0627\\u0644\\u0629 \\u062a\\u0643\\u0627\\u0633\\u064a \\u0623\\u062c\\u0631\\u0629 \\u062a\\u062d\\u062a \\u0627\\u0644\\u0637\\u0644\\u0628\",\"url\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/carsofq8.com\\\/ads\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/TAWSILA-TAXI-400.png?fit=400%2C223&ssl=1\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/89\\\/#organizationLogo\",\"width\":400,\"height\":223,\"caption\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u062a\\u0648\\u0635\\u064a\\u0644\\u0629 \\u0627\\u0644\\u0643\\u0648\\u064a\\u062a\"},\"image\":{\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/89\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/#website\",\"url\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/\",\"name\":\"\\u062a\\u0627\\u0643\\u0633\\u064a \\u062a\\u0648\\u0635\\u064a\\u0644\\u0629 \\u0627\\u0644\\u0643\\u0648\\u064a\\u062a\",\"description\":\"\\u0627\\u0631\\u0642\\u0627\\u0645 \\u062a\\u0627\\u0643\\u0633\\u064a \\u0648\\u0628\\u062f\\u0627\\u0644\\u0629 \\u062a\\u0643\\u0627\\u0633\\u064a \\u0623\\u062c\\u0631\\u0629 \\u062a\\u062d\\u062a \\u0627\\u0644\\u0637\\u0644\\u0628\",\"inLanguage\":\"ar\",\"publisher\":{\"@id\":\"https:\\\/\\\/carsofq8.com\\\/ads\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u062a\u0627\u0643\u0633\u064a \u0641\u064a \u0645\u0634\u0631\u0641 | \u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a","description":"","canonical_url":"https:\/\/carsofq8.com\/ads\/tag\/%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/89\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carsofq8.com\/ads#listItem","position":1,"name":"Home","item":"https:\/\/carsofq8.com\/ads","nextItem":{"@type":"ListItem","@id":"https:\/\/carsofq8.com\/ads\/tag\/%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81\/#listItem","name":"\u062a\u0627\u0643\u0633\u064a \u0641\u064a \u0645\u0634\u0631\u0641"}},{"@type":"ListItem","@id":"https:\/\/carsofq8.com\/ads\/tag\/%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81\/#listItem","position":2,"name":"\u062a\u0627\u0643\u0633\u064a \u0641\u064a \u0645\u0634\u0631\u0641","previousItem":{"@type":"ListItem","@id":"https:\/\/carsofq8.com\/ads#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/89\/#collectionpage","url":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/89\/","name":"\u062a\u0627\u0643\u0633\u064a \u0641\u064a \u0645\u0634\u0631\u0641 | \u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a","inLanguage":"ar","isPartOf":{"@id":"https:\/\/carsofq8.com\/ads\/#website"},"breadcrumb":{"@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/89\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/carsofq8.com\/ads\/#organization","name":"\u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a","description":"\u0627\u0631\u0642\u0627\u0645 \u062a\u0627\u0643\u0633\u064a \u0648\u0628\u062f\u0627\u0644\u0629 \u062a\u0643\u0627\u0633\u064a \u0623\u062c\u0631\u0629 \u062a\u062d\u062a \u0627\u0644\u0637\u0644\u0628","url":"https:\/\/carsofq8.com\/ads\/","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/carsofq8.com\/ads\/wp-content\/uploads\/2020\/02\/TAWSILA-TAXI-400.png?fit=400%2C223&ssl=1","@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/89\/#organizationLogo","width":400,"height":223,"caption":"\u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a"},"image":{"@id":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/89\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/carsofq8.com\/ads\/#website","url":"https:\/\/carsofq8.com\/ads\/","name":"\u062a\u0627\u0643\u0633\u064a \u062a\u0648\u0635\u064a\u0644\u0629 \u0627\u0644\u0643\u0648\u064a\u062a","description":"\u0627\u0631\u0642\u0627\u0645 \u062a\u0627\u0643\u0633\u064a \u0648\u0628\u062f\u0627\u0644\u0629 \u062a\u0643\u0627\u0633\u064a \u0623\u062c\u0631\u0629 \u062a\u062d\u062a \u0627\u0644\u0637\u0644\u0628","inLanguage":"ar","publisher":{"@id":"https:\/\/carsofq8.com\/ads\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/carsofq8.com\/ads\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u062a\u0627\u0643\u0633\u064a \u0641\u064a \u0645\u0634\u0631\u0641\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/carsofq8.com\/ads"},{"label":"\u062a\u0627\u0643\u0633\u064a \u0641\u064a \u0645\u0634\u0631\u0641","link":"https:\/\/carsofq8.com\/ads\/tag\/%d8%aa%d8%a7%d9%83%d8%b3%d9%8a-%d9%81%d9%8a-%d9%85%d8%b4%d8%b1%d9%81\/"}],"_links":{"self":[{"href":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/carsofq8.com\/ads\/wp-json\/wp\/v2\/posts?tags=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}